{"id":4015,"date":"2024-05-07T11:11:59","date_gmt":"2024-05-07T09:11:59","guid":{"rendered":"https:\/\/lagreska.es\/?page_id=4015"},"modified":"2024-05-28T10:31:38","modified_gmt":"2024-05-28T08:31:38","slug":"fuego","status":"publish","type":"page","link":"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/fuego\/","title":{"rendered":"Foc"},"content":{"rendered":"<style>.kb-row-layout-id4015_f681ad-6e > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id4015_f681ad-6e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id4015_f681ad-6e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:99px;padding-bottom:100px;min-height:580px;grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id4015_f681ad-6e{border-top-left-radius:0px;border-bottom-right-radius:0px;}.kb-row-layout-id4015_f681ad-6e{background-image:url('https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg');background-size:cover;background-position:47% 39%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id4015_f681ad-6e > .kt-row-layout-overlay{opacity:0.40;background-color:var(--global-palette3, #1A202C);mix-blend-mode:multiply;}.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep svg{width:118%;}.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep svg{fill:var(--global-palette8, #F7FAFC)!important;}@media all and (max-width: 1024px){.kb-row-layout-id4015_f681ad-6e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id4015_f681ad-6e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id4015_f681ad-6e .kt-row-layout-bottom-sep svg{width:%;}}.kt-row-layout-bottom-sep {z-index: 90;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4015_f681ad-6e alignnone has-theme-palette4-background-color kt-row-has-bg hero-section wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-waves\"><svg viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\"><path d=\"M1000,40c0,0 -120.077,-38.076 -250,-38c-129.923,0.076 -345.105,78 -500,78c-154.895,0 -250,-30 -250,-30l0,50l1000,0l0,-60Z\" \/><path d=\"M1000,40c0,0 -120.077,-38.076 -250,-38c-129.923,0.076 -345.105,73 -500,73c-154.895,0 -250,-45 -250,-45l0,70l1000,0l0,-60Z\" style=\"opacity: 0.4\" \/><path d=\"M1000,40c0,0 -120.077,-38.076 -250,-38c-129.923,0.076 -345.105,68 -500,68c-154.895,0 -250,-65 -250,-65l0,95l1000,0l0,-60Z\" style=\"opacity: 0.4\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col{padding-top:100px;padding-bottom:100px;}.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col,.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_b2f1b1-47{position:relative;}.kadence-column4015_b2f1b1-47, .kt-inside-inner-col > .kadence-column4015_b2f1b1-47:not(.specificity){margin-right:-50px;}@media all and (max-width: 1024px){.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_b2f1b1-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_b2f1b1-47 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64, .wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64[data-kb-block=\"kb-adv-heading4015_d8159d-64\"]{margin-right:-150px;text-align:left;font-weight:400;font-style:normal;font-family:'Lilita One';text-transform:none;letter-spacing:1px;}.wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64[data-kb-block=\"kb-adv-heading4015_d8159d-64\"] mark.kt-highlight{font-style:normal;color:var(--global-palette9, #ffffff);text-transform:capitalize;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:20px;}.wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64[data-kb-block=\"kb-adv-heading4015_d8159d-64\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64, .wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64[data-kb-block=\"kb-adv-heading4015_d8159d-64\"]{margin-right:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64, .wp-block-kadence-advancedheading.kt-adv-heading4015_d8159d-64[data-kb-block=\"kb-adv-heading4015_d8159d-64\"]{margin-right:0px;}}<\/style>\n<h1 class=\"kt-adv-heading4015_d8159d-64 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4015_d8159d-64\">Endinsa&#039;t a l&#039;apassionant m\u00f3n dels espectacles amb foc!<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4015_036c5c-59, .wp-block-kadence-advancedheading.kt-adv-heading4015_036c5c-59[data-kb-block=\"kb-adv-heading4015_036c5c-59\"]{text-align:left;font-weight:100;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4015_036c5c-59 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4015_036c5c-59[data-kb-block=\"kb-adv-heading4015_036c5c-59\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4015_036c5c-59 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4015_036c5c-59[data-kb-block=\"kb-adv-heading4015_036c5c-59\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading4015_036c5c-59 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4015_036c5c-59\">Deixa&#039;t embolicar pel riure i l&#039;emoci\u00f3 amb els nostres espectacles dissenyats especialment pels m\u00e9s petits. Des de divertides entremaliadures fins a impressionants il\u00b7lusions, cada xou \u00e9s una aventura \u00fanica que encantar\u00e0 a tota la fam\u00edlia.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4015_8b9888-a5 > .kt-inside-inner-col{padding-top:100px;}.kadence-column4015_8b9888-a5 > .kt-inside-inner-col,.kadence-column4015_8b9888-a5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_8b9888-a5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_8b9888-a5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_8b9888-a5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_8b9888-a5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_8b9888-a5{position:relative;}@media all and (max-width: 1024px){.kadence-column4015_8b9888-a5 > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_8b9888-a5 > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_8b9888-a5 inner-column-2\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4015_4eafc2-92 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4015_4eafc2-92 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4015_4eafc2-92 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-lg, 4rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4015_4eafc2-92 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4015_4eafc2-92 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4015_4eafc2-92 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4015_4eafc2-92 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4015_992481-d4 > .kt-inside-inner-col,.kadence-column4015_992481-d4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_992481-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_992481-d4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_992481-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_992481-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_992481-d4{position:relative;}@media all and (max-width: 1024px){.kadence-column4015_992481-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_992481-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_992481-d4\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-kadence-query wp-block-kadence-query4015_ffae48-48 kadence-query-init kb-query-basic-style animation-overlay kb-query wp-block-kadence-query\" data-id=\"4485\" data-infinite-scroll=\"\">\n<style>.kb-pro-masonry-init .wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap{columns:3;}.kb-pro-masonry-init .wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap .kb-query-item{margin-bottom:var(--global-kb-gap-md, 2rem);}.wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap.kb-query-grid-wrap{grid-template-columns:repeat(3, 1fr);row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-md, 2rem);}.wp-block-kadence-query-card4015_251163-4f .kb-query-grid-wrap .kb-query-item.kb-query-block-post{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.1);background:var(--global-palette9, #ffffff);border-top-left-radius:16px;border-top-right-radius:16px;border-bottom-right-radius:16px;border-bottom-left-radius:16px;overflow:hidden;}@media all and (max-width: 1024px){.kb-pro-masonry-init .wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap{columns:2;}}@media all and (max-width: 1024px){.wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap.kb-query-grid-wrap{grid-template-columns:repeat(2, 1fr);}}@media all and (max-width: 767px){.kb-pro-masonry-init .wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap{columns:1;}.wp-block-kadence-query-card4015_251163-4f.wp-block-kadence-query-card .kb-query-grid-wrap.kb-query-grid-wrap{grid-template-columns:repeat(1, 1fr);}}<\/style><div class=\"wp-block-kadence-query-card4015_251163-4f wp-block-kadence-query-card\" data-max-num-pages=\"1\"><div class=\"overlay\"><\/div><ul class=\"kb-query-grid-wrap\" data-item-selector=\"kb-query-item\"><li class=\"kb-query-item kb-query-block-post post-4405 artista type-artista status-publish has-post-thumbnail hentry espectaculos-fuego\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col,.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_f53b0b-8f4405{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_f53b0b-8f4405 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_f53b0b-8f4405 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4603_7332fb-e5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4603_7332fb-e5 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4603_5465f7-3a > .kt-inside-inner-col,.kadence-column4603_5465f7-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_5465f7-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_5465f7-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4603_d77dbc-80:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4603_d77dbc-80 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4603_d77dbc-80 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-768x432.jpg\" alt=\"\" width=\"768\" height=\"432\" class=\"kb-img wp-image-3956\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-768x432.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-300x169.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-1024x576.jpg 1024w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-1536x864.jpg 1536w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4603_c1d845-1d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4603_c1d845-1d > .kt-inside-inner-col,.kadence-column4603_c1d845-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_c1d845-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_c1d845-1d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:24px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4603_73ef18-ca wp-block-kadence-advancedheading has-theme-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading4603_73ef18-ca\">Peces de foc nocturn<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4603_5181c5-85 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4603_5181c5-85\"><p>Durada: 1h<\/p>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/baile-con-fuego\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4403 artista type-artista status-publish has-post-thumbnail hentry espectaculos-fuego\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col,.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_f53b0b-8f4403{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_f53b0b-8f4403 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_f53b0b-8f4403 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4603_7332fb-e5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4603_7332fb-e5 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4603_5465f7-3a > .kt-inside-inner-col,.kadence-column4603_5465f7-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_5465f7-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_5465f7-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4603_d77dbc-80:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4603_d77dbc-80 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4603_d77dbc-80 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/lagreska-23-768x432.jpg\" alt=\"\" width=\"768\" height=\"432\" class=\"kb-img wp-image-3743\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/lagreska-23-768x432.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/lagreska-23-300x169.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/lagreska-23-1024x576.jpg 1024w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/lagreska-23-1536x864.jpg 1536w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/lagreska-23.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4603_c1d845-1d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4603_c1d845-1d > .kt-inside-inner-col,.kadence-column4603_c1d845-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_c1d845-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_c1d845-1d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:24px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4603_73ef18-ca wp-block-kadence-advancedheading has-theme-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading4603_73ef18-ca\">En flames<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4603_5181c5-85 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4603_5181c5-85\"><p>Durada: 1h<\/p>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/en-llamas\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4400 artista type-artista status-publish has-post-thumbnail hentry espectaculos-fuego\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col,.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_f53b0b-8f4400{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_f53b0b-8f4400 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_f53b0b-8f4400 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4603_7332fb-e5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4603_7332fb-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4603_7332fb-e5 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4603_5465f7-3a > .kt-inside-inner-col,.kadence-column4603_5465f7-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_5465f7-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_5465f7-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_5465f7-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_5465f7-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4603_d77dbc-80:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4603_d77dbc-80 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4603_d77dbc-80 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/disco.jpeg\" alt=\"\" width=\"691\" height=\"476\" class=\"kb-img wp-image-3884\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/disco.jpeg 691w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/disco-300x207.jpeg 300w\" sizes=\"auto, (max-width: 691px) 100vw, 691px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4603_c1d845-1d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4603_c1d845-1d > .kt-inside-inner-col,.kadence-column4603_c1d845-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4603_c1d845-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4603_c1d845-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4603_c1d845-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4603_c1d845-1d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:24px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4603_73ef18-ca[data-kb-block=\"kb-adv-heading4603_73ef18-ca\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4603_73ef18-ca wp-block-kadence-advancedheading has-theme-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading4603_73ef18-ca\">Festival amb foc!<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4603_5181c5-85[data-kb-block=\"kb-adv-heading4603_5181c5-85\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4603_5181c5-85 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4603_5181c5-85\"><p>Suraci\u00f3: 1h<\/p>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/festival-con-fuego\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><\/ul><\/div>\n<\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4015_72a764-fd > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id4015_72a764-fd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id4015_72a764-fd > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:100px;padding-bottom:100px;grid-template-columns:minmax(0, calc(60% - ((80px * 1 )\/2)))minmax(0, calc(40% - ((80px * 1 )\/2)));}.kb-row-layout-id4015_72a764-fd{background-color:#ff8d66;}.kb-row-layout-id4015_72a764-fd > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id4015_72a764-fd .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id4015_72a764-fd .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id4015_72a764-fd .kt-row-layout-top-sep svg{fill:var(--global-palette8, #F7FAFC)!important;}@media all and (max-width: 1024px){.kb-row-layout-id4015_72a764-fd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4015_72a764-fd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id4015_72a764-fd .rounded-corners {  border-radius: 70px;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4015_72a764-fd alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-top-sep kt-row-sep-type-crvli\"><svg viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\"><path d=\"M1000,0c0,0 -420.987,98 -650,98c-229.013,0 -350,-98 -350,-98l0,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col,.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_fd3dc6-25{position:relative;}@media all and (max-width: 1024px){.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_fd3dc6-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_fd3dc6-25 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4015_3381bb-fc:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-md, 2rem);}.kb-image4015_3381bb-fc .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image4015_3381bb-fc img.kb-img, .kb-image4015_3381bb-fc .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4015_3381bb-fc kb-image-is-ratio-size rounded-corners\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/91.jpg\" alt=\"\" class=\"kb-img wp-image-5951\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/91.jpg 1920w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/91-300x169.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/91-1024x576.jpg 1024w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/91-768x432.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/91-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/figure>\n\n\n<style>.kb-row-layout-id4015_688202-9c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4015_688202-9c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4015_688202-9c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:25px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4015_688202-9c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4015_688202-9c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4015_688202-9c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4015_688202-9c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column4015_b957be-a0 > .kt-inside-inner-col,.kadence-column4015_b957be-a0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_b957be-a0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_b957be-a0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_b957be-a0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_b957be-a0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_b957be-a0{position:relative;}@media all and (max-width: 1024px){.kadence-column4015_b957be-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_b957be-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_b957be-a0 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image4015_5a0a98-65 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image4015_5a0a98-65 img.kb-img, .kb-image4015_5a0a98-65 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4015_5a0a98-65 kb-image-is-ratio-size rounded-corners\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/90.jpg\" alt=\"\" class=\"kb-img wp-image-5950\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/90.jpg 1920w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/90-300x169.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/90-1024x576.jpg 1024w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/90-768x432.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/90-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4015_b41b7e-6f > .kt-inside-inner-col,.kadence-column4015_b41b7e-6f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_b41b7e-6f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_b41b7e-6f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_b41b7e-6f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_b41b7e-6f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_b41b7e-6f{position:relative;}@media all and (max-width: 1024px){.kadence-column4015_b41b7e-6f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_b41b7e-6f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_b41b7e-6f inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image4015_92cab3-a1 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image4015_92cab3-a1 img.kb-img, .kb-image4015_92cab3-a1 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4015_92cab3-a1 kb-image-is-ratio-size rounded-corners\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/92.jpg\" alt=\"\" class=\"kb-img wp-image-5952\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/92.jpg 1920w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/92-300x169.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/92-1024x576.jpg 1024w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/92-768x432.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/92-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column4015_743328-ed > .kt-inside-inner-col,.kadence-column4015_743328-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4015_743328-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4015_743328-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column4015_743328-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4015_743328-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4015_743328-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column4015_743328-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4015_743328-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4015_743328-ed inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15, .wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15[data-kb-block=\"kb-adv-heading4015_e8f186-15\"]{margin-top:0px;text-align:left;font-weight:400;font-style:normal;font-family:'Lilita One';color:#1c232e;}.wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15[data-kb-block=\"kb-adv-heading4015_e8f186-15\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15[data-kb-block=\"kb-adv-heading4015_e8f186-15\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15, .wp-block-kadence-advancedheading.kt-adv-heading4015_e8f186-15[data-kb-block=\"kb-adv-heading4015_e8f186-15\"]{font-size:32px;}}<\/style>\n<h2 class=\"kt-adv-heading4015_e8f186-15 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4015_e8f186-15\">Nits de foc i passi\u00f3 al teu esdeveniment<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4015_f3f215-6e, .wp-block-kadence-advancedheading.kt-adv-heading4015_f3f215-6e[data-kb-block=\"kb-adv-heading4015_f3f215-6e\"]{text-align:left;font-weight:300;font-style:normal;color:#1e2931;}.wp-block-kadence-advancedheading.kt-adv-heading4015_f3f215-6e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4015_f3f215-6e[data-kb-block=\"kb-adv-heading4015_f3f215-6e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4015_f3f215-6e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4015_f3f215-6e[data-kb-block=\"kb-adv-heading4015_f3f215-6e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading4015_f3f215-6e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4015_f3f215-6e\">Sent l&#039;adrenalina rec\u00f3rrer el teu cos amb els nostres espectacles enlluernadors de foc a la Greska. Els nostres artistes encendren la nit amb la seva passi\u00f3 i habilitat. Contacta&#039;ns avui mateix per reservar el teu espectacle de foc<\/p>\n\n\n<style>.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form textarea{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advanced-form3986-cpt-id{--kb-form-border-width:2px;--kb-form-border-color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form textarea{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form textarea{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form3986-cpt-id kb-adv-form-label-style-normal kb-adv-form-input-size-small kb-form-basic-style wp-block-kadence-advanced-form\"><form id=\"kb-adv-form-3986-cpt-id\" class=\"kb-advanced-form\" method=\"post\" action=\"\">\n<style>.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-sm, 1rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3986_1bf7d7-03 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3986_1bf7d7-03 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3986_b30672-90 > .kt-inside-inner-col,.kadence-column3986_b30672-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_b30672-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_b30672-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_b30672-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_b30672-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_b30672-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_b30672-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_b30672-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_b30672-90\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986f4fb11-e7 wp-block-kadence-advanced-form-text\"><input name=\"fieldf4fb11-e7\" id=\"field3986f4fb11-e7\" data-label=\"Nombre y Apellidos\" type=\"text\" placeholder=\"Nom i Cognoms\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Nom i Cognoms\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_d76a19-ed > .kt-inside-inner-col,.kadence-column3986_d76a19-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_d76a19-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_d76a19-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_d76a19-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_d76a19-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_d76a19-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_d76a19-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_d76a19-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_d76a19-ed\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986fcd365-83 wp-block-kadence-advanced-form-email\"><input name=\"fieldfcd365-83\" id=\"field3986fcd365-83\" data-label=\"Correo electr\u00f3nico\" type=\"email\" placeholder=\"Correu electr\u00f2nic\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Correu electr\u00f2nic\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col,.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_2d67dc-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_2d67dc-c0\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986c2f560-81 wp-block-kadence-advanced-form-telephone\"><input name=\"fieldc2f560-81\" id=\"field3986c2f560-81\" data-label=\"Tel\u00e9fono\" type=\"tel\" placeholder=\"Tel\u00e8fon\" value=\"\" data-type=\"tel\" class=\"kb-field kb-tel-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Tel\u00e8fon\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_c63fa2-08 > .kt-inside-inner-col,.kadence-column3986_c63fa2-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_c63fa2-08{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_c63fa2-08\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986138b5e-fd wp-block-kadence-advanced-form-text\"><input name=\"field138b5e-fd\" id=\"field3986138b5e-fd\" data-label=\"Prov\u00edncia\" type=\"text\" placeholder=\"Prov\u00edncia\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Prov\u00edncia\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col,.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_f7f44f-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_f7f44f-b5\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field39868762a4-7d wp-block-kadence-advanced-form-select\"><select  name=\"field8762a4-7d\" id=\"field39868762a4-7d\" required aria-required=\"true\" aria-label=\"Servei\"><option value=\"Espect\u00e1culo y animaci\u00f3n\">Espectacle i animaci\u00f3<\/option><option value=\"M\u00fasica para eventos\">M\u00fasica per a esdeveniments<\/option><option value=\"Parques y atracciones\">Parcs i atraccions<\/option><option value=\"Alquiler  de material\">Lloguer de material<\/option><option value=\"Organizaci\u00f3n de eventos\">Organitzaci\u00f3 d&#039;esdeveniments<\/option><\/select><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col,.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_c7c1a4-5e{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_c7c1a4-5e\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986aba617-98 wp-block-kadence-advanced-form-text\"><input name=\"fieldaba617-98\" id=\"field3986aba617-98\" data-label=\"Asunto\" type=\"text\" placeholder=\"Assumpte\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Assumpte\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986cc8e76-97 wp-block-kadence-advanced-form-textarea\"><textarea name=\"fieldcc8e76-97\" id=\"field3986cc8e76-97\" rows=\"3\"  data-label=\"Consulta\" placeholder=\"Consulta\" data-type=\"textarea\" class=\"kb-field kb-textarea-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Consulta\"><\/textarea><\/div>\n\n<div class=\"kb-adv-form-field kb-field39860ab9ec-bb wp-block-kadence-advanced-form-accept\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb39860ab9ec-bb\" data-type=\"accept\" data-required=\"yes\" ><legend class=\"screen-reader-text\">Privadesa<\/legend><div class=\"kb-radio-check-item\"><input name=\"field0ab9ec-bb\" id=\"field39860ab9ec-bb_0\" data-label=\"Privacidad\" type=\"checkbox\" value=\"accept\" data-type=\"accept\" class=\"kb-field kb-accept-field kb-checkbox-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Privadesa\"\/><label for=\"field39860ab9ec-bb_0\">He llegit i accepto les condicions contingudes a la <a href=\"https:\/\/lagreska.es\/ca\/politica-de-privacidad\/\" data-type=\"page\" data-id=\"10\">pol\u00edtica de privadesa<\/a> sobre el tractament de les meves dades per gestionar la meva consulta o petici\u00f3.<span class=\"kb-adv-form-required\">*<\/span><\/label><\/div><\/fieldset><\/div>\n\n<input type=\"hidden\" name=\"recaptcha_response\" class=\"kb_recaptcha_response kb_recaptcha_2d1c95-b1\" \/>\n\n<style>.kb-submit-field .kb-btn3087cc-e8.kb-button, ul.menu .kb-submit-field .kb-btn3087cc-e8.kb-button{width:200px;}.kb-submit-field .kb-btn3087cc-e8.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.kb-submit-field .kb-btn3087cc-e8.kb-button:hover, .kb-submit-field .kb-btn3087cc-e8.kb-button:focus{color:var(--global-palette1, #3182CE);background:var(--global-palette9, #ffffff);}.kb-submit-field.kb-field3087cc-e8{justify-content:flex-start;}@media all and (max-width: 1024px){.kb-submit-field .kb-btn3087cc-e8.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.kb-submit-field .kb-btn3087cc-e8.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-field3087cc-e8 wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btn3087cc-e8 kt-btn-size-standard kt-btn-width-type-fixed kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false\" type=\"submit\"><span class=\"kt-btn-inner-text\">Enviar<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"3986\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"3986-cpt-id\"><input type=\"hidden\" name=\"trp-form-language\" value=\"ca\"\/><\/form><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Endinsa&#039;t a l&#039;apassionant m\u00f3n dels espectacles amb foc! Deixa&#039;t embolicar pel riure i l&#039;emoci\u00f3 amb els nostres espectacles dissenyats especialment pels m\u00e9s petits. Des de divertides entremaliadures fins a impressionants il\u00b7lusions, cada xou \u00e9s una aventura \u00fanica que encantar\u00e0 a tota la fam\u00edlia. Nits de foc i passi\u00f3 al teu esdeveniment Sent la\u2026<\/p>","protected":false},"author":1,"featured_media":3956,"parent":3682,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-4015","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fuego - La Greska Espectacles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/fuego\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuego - La Greska Espectacles\" \/>\n<meta property=\"og:description\" content=\"\u00a1Ad\u00e9ntrate en el apasionante mundo de los espect\u00e1culos con fuego! D\u00e9jate envolver por la risa y la emoci\u00f3n con nuestros espect\u00e1culos dise\u00f1ados especialmente para los m\u00e1s peque\u00f1os. Desde divertidas travesuras hasta impresionantes ilusiones, cada show es una aventura \u00fanica que encantar\u00e1 a toda la familia. Noches de fuego y pasi\u00f3n en tu evento Siente la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/fuego\/\" \/>\n<meta property=\"og:site_name\" content=\"La Greska Espectacles\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T08:31:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/\",\"url\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/\",\"name\":\"Fuego - La Greska Espectacles\",\"isPartOf\":{\"@id\":\"https:\/\/lagreska.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg\",\"datePublished\":\"2024-05-07T09:11:59+00:00\",\"dateModified\":\"2024-05-28T08:31:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#primaryimage\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lagreska.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espect\u00e1culos y Animaci\u00f3n\",\"item\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fuego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lagreska.es\/#website\",\"url\":\"https:\/\/lagreska.es\/\",\"name\":\"La Greska Espectacles\",\"description\":\"Agencia de animaci\u00f3n de fiestas y eventos en Sabadell\",\"publisher\":{\"@id\":\"https:\/\/lagreska.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lagreska.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lagreska.es\/#organization\",\"name\":\"La Greska Espectacles\",\"url\":\"https:\/\/lagreska.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":813,\"height\":307,\"caption\":\"La Greska Espectacles\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fuego - La Greska Espectacles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/fuego\/","og_locale":"ca_ES","og_type":"article","og_title":"Fuego - La Greska Espectacles","og_description":"\u00a1Ad\u00e9ntrate en el apasionante mundo de los espect\u00e1culos con fuego! D\u00e9jate envolver por la risa y la emoci\u00f3n con nuestros espect\u00e1culos dise\u00f1ados especialmente para los m\u00e1s peque\u00f1os. Desde divertidas travesuras hasta impresionantes ilusiones, cada show es una aventura \u00fanica que encantar\u00e1 a toda la familia. Noches de fuego y pasi\u00f3n en tu evento Siente la...","og_url":"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/fuego\/","og_site_name":"La Greska Espectacles","article_modified_time":"2024-05-28T08:31:38+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/","url":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/","name":"Fuego - La Greska Espectacles","isPartOf":{"@id":"https:\/\/lagreska.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#primaryimage"},"image":{"@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#primaryimage"},"thumbnailUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg","datePublished":"2024-05-07T09:11:59+00:00","dateModified":"2024-05-28T08:31:38+00:00","breadcrumb":{"@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#primaryimage","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/fuego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagreska.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Espect\u00e1culos y Animaci\u00f3n","item":"https:\/\/lagreska.es\/espectaculos-y-animacion\/"},{"@type":"ListItem","position":3,"name":"Fuego"}]},{"@type":"WebSite","@id":"https:\/\/lagreska.es\/#website","url":"https:\/\/lagreska.es\/","name":"La Greska Espectacles","description":"Ag\u00e8ncia d&#039;animaci\u00f3 de festes i esdeveniments a Sabadell","publisher":{"@id":"https:\/\/lagreska.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagreska.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagreska.es\/#organization","name":"La Greska Espectacles","url":"https:\/\/lagreska.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","width":813,"height":307,"caption":"La Greska Espectacles"},"image":{"@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/espectaculo-con-fuego-1024x576.jpg",1024,576,true],"author_info":{"display_name":"eloi","author_link":"https:\/\/lagreska.es\/ca\/author\/eloi\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages\/4015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/comments?post=4015"}],"version-history":[{"count":0,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages\/4015\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages\/3682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media\/3956"}],"wp:attachment":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media?parent=4015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}