{"id":4011,"date":"2024-05-07T11:09:00","date_gmt":"2024-05-07T09:09:00","guid":{"rendered":"https:\/\/lagreska.es\/?page_id=4011"},"modified":"2024-05-29T09:19:55","modified_gmt":"2024-05-29T07:19:55","slug":"cuentos","status":"publish","type":"page","link":"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/cuentos\/","title":{"rendered":"Contes"},"content":{"rendered":"<style>.kb-row-layout-id4011_4bb466-3d > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id4011_4bb466-3d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id4011_4bb466-3d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:99px;padding-bottom:100px;min-height:580px;grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id4011_4bb466-3d{border-top-left-radius:0px;border-bottom-right-radius:0px;}.kb-row-layout-id4011_4bb466-3d{background-image:url('https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/circo-scaled.jpg');background-size:cover;background-position:47% 39%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id4011_4bb466-3d > .kt-row-layout-overlay{opacity:0.40;background-color:var(--global-palette3, #1A202C);mix-blend-mode:multiply;}.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep svg{width:118%;}.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep svg{fill:var(--global-palette8, #F7FAFC)!important;}@media all and (max-width: 1024px){.kb-row-layout-id4011_4bb466-3d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id4011_4bb466-3d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id4011_4bb466-3d .kt-row-layout-bottom-sep svg{width:%;}}.kt-row-layout-bottom-sep {z-index: 90;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_4bb466-3d alignnone has-theme-palette4-background-color kt-row-has-bg hero-section wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-waves\"><svg viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\"><path d=\"M1000,40c0,0 -120.077,-38.076 -250,-38c-129.923,0.076 -345.105,78 -500,78c-154.895,0 -250,-30 -250,-30l0,50l1000,0l0,-60Z\" \/><path d=\"M1000,40c0,0 -120.077,-38.076 -250,-38c-129.923,0.076 -345.105,73 -500,73c-154.895,0 -250,-45 -250,-45l0,70l1000,0l0,-60Z\" style=\"opacity: 0.4\" \/><path d=\"M1000,40c0,0 -120.077,-38.076 -250,-38c-129.923,0.076 -345.105,68 -500,68c-154.895,0 -250,-65 -250,-65l0,95l1000,0l0,-60Z\" style=\"opacity: 0.4\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column4011_546e9f-ce > .kt-inside-inner-col{padding-top:100px;padding-bottom:100px;}.kadence-column4011_546e9f-ce > .kt-inside-inner-col,.kadence-column4011_546e9f-ce > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_546e9f-ce > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_546e9f-ce > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_546e9f-ce > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_546e9f-ce > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_546e9f-ce{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_546e9f-ce > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_546e9f-ce > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_546e9f-ce inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3, .wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3[data-kb-block=\"kb-adv-heading4011_a008b8-c3\"]{margin-right:-150px;text-align:left;font-weight:400;font-style:normal;font-family:'Lilita One';text-transform:none;letter-spacing:1px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3[data-kb-block=\"kb-adv-heading4011_a008b8-c3\"] mark.kt-highlight{font-style:normal;color:var(--global-palette9, #ffffff);text-transform:capitalize;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:20px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3[data-kb-block=\"kb-adv-heading4011_a008b8-c3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3, .wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3[data-kb-block=\"kb-adv-heading4011_a008b8-c3\"]{margin-right:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3, .wp-block-kadence-advancedheading.kt-adv-heading4011_a008b8-c3[data-kb-block=\"kb-adv-heading4011_a008b8-c3\"]{margin-right:0px;}}<\/style>\n<h1 class=\"kt-adv-heading4011_a008b8-c3 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4011_a008b8-c3\">Viatja a un m\u00f3n de fantasia amb els nostres contes encantats!<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_7c92fc-aa, .wp-block-kadence-advancedheading.kt-adv-heading4011_7c92fc-aa[data-kb-block=\"kb-adv-heading4011_7c92fc-aa\"]{text-align:left;font-weight:100;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_7c92fc-aa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_7c92fc-aa[data-kb-block=\"kb-adv-heading4011_7c92fc-aa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_7c92fc-aa img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_7c92fc-aa[data-kb-block=\"kb-adv-heading4011_7c92fc-aa\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading4011_7c92fc-aa wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4011_7c92fc-aa\">Deixa&#039;t embolicar per la m\u00e0gia dels contes amb La Greska Espectacles! Submergeix-te en un univers ple de rialles, emoci\u00f3 i aventures dissenyades especialment per als m\u00e9s petits i tota la fam\u00edlia. Des de divertides entremaliadures fins a impressionants il\u00b7lusions, cadascun dels nostres espectacles \u00e9s una experi\u00e8ncia \u00fanica que encantar\u00e0 a grans i nois per igual.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col{padding-top:100px;}.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col,.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_cbe1ad-88{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_cbe1ad-88 > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_cbe1ad-88 inner-column-2\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4011_482b26-62 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_482b26-62 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_482b26-62 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4011_482b26-62 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_482b26-62 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_482b26-62 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_482b26-62 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_24d8e1-cd > .kt-inside-inner-col,.kadence-column4011_24d8e1-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_24d8e1-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_24d8e1-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_24d8e1-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_24d8e1-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_24d8e1-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_24d8e1-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_24d8e1-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_24d8e1-cd\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-kadence-query wp-block-kadence-query4011_074ab1-05 kadence-query-init kb-query-basic-style animation-overlay kb-query wp-block-kadence-query\" data-id=\"4166\" data-infinite-scroll=\"\">\n<style>.kb-pro-masonry-init .wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap{columns:1;}.kb-pro-masonry-init .wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap .kb-query-item{margin-bottom:var(--global-kb-gap-md, 2rem);}.wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap.kb-query-grid-wrap{grid-template-columns:repeat(1, 1fr);row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-md, 2rem);}.wp-block-kadence-query-card4011_f472ec-65 .kb-query-grid-wrap .kb-query-item.kb-query-block-post{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.1);background:var(--global-palette9, #ffffff);border-top-left-radius:16px;border-top-right-radius:16px;border-bottom-right-radius:16px;border-bottom-left-radius:16px;overflow:hidden;}@media all and (max-width: 1024px){.kb-pro-masonry-init .wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap{columns:2;}}@media all and (max-width: 1024px){.wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap.kb-query-grid-wrap{grid-template-columns:repeat(2, 1fr);}}@media all and (max-width: 767px){.kb-pro-masonry-init .wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap{columns:1;}.wp-block-kadence-query-card4011_f472ec-65.wp-block-kadence-query-card .kb-query-grid-wrap.kb-query-grid-wrap{grid-template-columns:repeat(1, 1fr);}}<\/style><div class=\"wp-block-kadence-query-card4011_f472ec-65 wp-block-kadence-query-card\" data-max-num-pages=\"1\"><div class=\"overlay\"><\/div><ul class=\"kb-query-grid-wrap\" data-item-selector=\"kb-query-item\"><li class=\"kb-query-item kb-query-block-post post-4092 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos espectaculos-humor\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4092{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4092 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4092 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096271.jpg\" alt=\"\" width=\"355\" height=\"242\" class=\"kb-img wp-image-4097\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096271.jpg 355w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096271-300x205.jpg 300w\" sizes=\"auto, (max-width: 355px) 100vw, 355px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">\u00ab\u00c0NIMA, EL PATUFET I LA RATETA\u00bb<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>TP \u00b7 Catal\u00e0\/Castell\u00e0 \u00b7 50Min (90min\/75min) \u00b7 4x4m \u00b7 1500Watts \u00b7 So<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>L&#039;\u00c0nima ens presentar\u00e0 dos contes cl\u00e0ssics, coneguts per tothom:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A Pituso:<\/strong> explicat i teatralitzat amb lajuda dalgun voluntari del p\u00fablic.<\/li>\n\n\n\n<li><strong>La rateta que escombra l&#039;escaleta: <\/strong>a c\u00e0rrec d&#039;uns titelles simp\u00e0tics i divertits que s&#039;amaguen dins d&#039;un teatret.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/alma-el-patufet-i-la-rateta\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4093 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4093{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4093 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4093 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096270.jpg\" alt=\"\" width=\"306\" height=\"209\" class=\"kb-img wp-image-4098\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096270.jpg 306w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096270-300x205.jpg 300w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">\u00abCOMTES EMPAPERATS\u00bb<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>TP \u00b7 Catal\u00e0\/Castell\u00e0 \u00b7 50min (3h\/90min) \u00b7 5x4m \u00b7 3000Watts \u00b7 So: 300Watts \u00b7 Il\u00b7luminaci\u00f3<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>El paper es transformar\u00e0 en decorat, personatges, objectes i elements quotidians. d&#039;aqu\u00ed el t\u00edtol \u00abcontes empaperats i personatges esborrajats\u00bb\u00a0<br><br>\u2013 Millor ser encantador i no encantat;<br>\u2013 El diari, el convidat i el llop afamat.<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/contes-empaperats\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4089 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4089{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4089 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4089 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096277.jpg\" alt=\"\" width=\"176\" height=\"120\" class=\"kb-img wp-image-4094\"><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">CIGRONET<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>0 \u2013 5 anys \u00b7 Catal\u00e0 \u00b7 60min ( 1h\/1h) \u00b7 4x3m \u00b7 4Kw \u00b7 So (2Kw) \u00b7<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>Un espectacle de titelles adre\u00e7at a nens de 0 a 5 anys. Amb els contes populars i tradicionals i un gui\u00f3 molt personalitzat. La caputxeta, en pit\u00f3s, la rateta i els tres garrins. Al final de l\u00b4espectacle, obrim el teatret perqu\u00e8 la mainada pugui veure i tocar totes les titelles de ben aprop.<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/cigronet\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4101 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4101{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4101 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4101 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096208-768x524.jpg\" alt=\"\" width=\"768\" height=\"524\" class=\"kb-img wp-image-4102\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096208-768x524.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096208-300x205.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096208.jpg 900w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">CONTES D&#039;AQUI I D&#039;ALLA I DE M\u00c9S ENLL\u00c0<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>TP \u00b7 Catala\/Castell\u00e0 \u00b7 50min (30min\/15min) \u00b7 3x3m \u00b7 1500Watts<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>Ens far\u00e0 descobrir tres contes arribats de diferents parts del m\u00f3n. S\u00f3n contes divertits, originals i plens de sorpreses.<\/p>\n\n\n\n<p>El nen que no tenia sort; El gat pisculets i la rata de biblioteca; Les tietes \u00e0vies vergonyoses<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/contes-daqui-i-dalla-i-de-mes-enlla\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4091 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4091{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4091 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4091 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096272.jpg\" alt=\"\" width=\"160\" height=\"110\" class=\"kb-img wp-image-4096\"><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">CONTES D&#039;INSTRUMENTS DEL M\u00d3N<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>+3 anys \u00b7 Catal\u00e0 \u00b7 45min (60min\/60min) \u00b7 4x3m \u00b7 3KW \u00b7 So \u00b7 Projecci\u00f3<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>A Rah-mi \u00e9s un xicot alt com un sant Pau, i es presenta en so de pau i de festa mostrant la bandera de la pau per presentar-nos un reguitzell de can\u00e7ons i de contes per fer les paus, no per fer la pau. Us convidem a participar-hi. Entre tots la farem grossa, posarem pau i ens repartirem a raig.<\/p>\n\n\n\n<p>Quan acabem, sense cap mena de recan\u00e7a, marxarem amb una branca d&#039;olivera i ens deixarem en pau.<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/cuentos-de-instrumentos-del-mundo\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4099 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4099{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4099 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4099 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096207.jpg\" alt=\"\" width=\"621\" height=\"427\" class=\"kb-img wp-image-4100\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096207.jpg 621w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096207-300x206.jpg 300w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">CONTES DELS GERMANS GRIMM<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>TP \u00b7 Catal\u00e0\/Castell\u00e0 \u00b7 45min (60min\/30min) \u00b7 3x3m \u00b7 1500Watts<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>Amb to pl\u00e0cid, entretingut i divertit qui van ser els germans grimm. Despr\u00e9s de manera din\u00e0mica, l&#039;\u00c0nima s&#039;endinsar\u00e0 en els contes, narrant-nos les hist\u00f2ries, interpretant diversos personatges i dirigint algun actor espontani triat entre els nens i les nenes del p\u00fablic. Els tres contes que explicar\u00e0 s\u00f3n el sastre valent, Els m\u00fasics de Bremen Caputxeta vermella.<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/cuentos-de-los-hermanos-grimm\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4090 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4090{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4090 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4090 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096276.jpg\" alt=\"\" width=\"579\" height=\"395\" class=\"kb-img wp-image-4095\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096276.jpg 579w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096276-300x205.jpg 300w\" sizes=\"auto, (max-width: 579px) 100vw, 579px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">GEGANTS I DRACS<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><div class=\"n module-type-text module-alias-loopSubTitle section-cls-big-text\">\n<p>+3 anys \u00b7 Catal\u00e0 \u00b7 50 min \u00b7<\/p>\n<\/div>\n<div class=\"n module-type-text module-alias-loopDescription section-cls-normal-text\"><\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>Una sessi\u00f3 de contes de petit format, per\u00f2 geganta. Amb can\u00e7ons i jocs d&#039;utillatge. Els personatges m\u00e9s gegantins dels contes sempre han encantat els m\u00e9s petits. Aquesta sessi\u00f3 trobareu algun parent lluny\u00e0 del gegant del Pi, la \u00abveritable\u00bb hist\u00f2ria del Drac de Sant Jordi i una petita hist\u00f2ria d&#039;un dels savis m\u00e9s savis de tot el m\u00f3n, el vell Nasred\u00edn. Obriu b\u00e9 els ulls i les orelles, que per all\u00e0 us entraran gegants i dracs! Per\u00f2 tingueu la boca tancada, que entren mosques\u2026<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/gigantes-i-dragones\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-10453 artista type-artista status-publish has-post-thumbnail hentry espectaculos-animacion espectaculos-cuentos espectaculos-personajes\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col,.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd10453{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd10453 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd10453 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes-768x445.jpg\" alt=\"\" width=\"768\" height=\"445\" class=\"kb-img wp-image-10454\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes-768x445.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes-300x174.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes-18x10.jpg 18w, https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">KARIBU<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<h3 class=\"wp-block-heading\"><strong>KARIBU! \u2013 M\u00fasica, Valores y Diversi\u00f3n para Toda la Familia<\/strong><\/h3>\n\n\n\n<p id=\"p-rc_0eb4050334d4bfe5-20\">En el cat\u00e1logo de <strong>La Greska<\/strong>, apostamos por espect\u00e1culos que no solo entretengan, sino que tambi\u00e9n dejen huella. <strong>KARIBU!<\/strong> es una propuesta de animaci\u00f3n musical din\u00e1mica y profundamente participativa, dise\u00f1ada para que ni\u00f1os, j\u00f3venes y adultos disfruten juntos de una experiencia \u00fanica<sup><\/sup>.<\/p>\n\n\n\n<p id=\"p-rc_0eb4050334d4bfe5-21\">A trav\u00e9s de <strong>canciones y danzas originales<\/strong>, este espect\u00e1culo invita al p\u00fablico a realizar un viaje musical centrado en valores fundamentales como los <strong>Derechos de los Infantes, la Cooperaci\u00f3n y la Solidaridad<\/strong><sup><\/sup>. Es la opci\u00f3n perfecta para eventos que buscan combinar la fiesta con un mensaje educativo y social.<\/p>\n\n\n\n<p><strong>Detalles del espect\u00e1culo:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Formato:<\/strong> Animaci\u00f3n musical con una puesta en escena activa que invita a la participaci\u00f3n constante del p\u00fablico.<\/li>\n\n\n\n<li><strong>Duraci\u00f3n:<\/strong> 60 minutos de ritmo y aprendizaje.<\/li>\n\n\n\n<li><strong>P\u00fablico:<\/strong> Un espect\u00e1culo transversal recomendado para <strong>todas las edades<\/strong>.<\/li>\n\n\n\n<li><strong>Tem\u00e0tica:<\/strong> Un recorrido l\u00fadico por la solidaridad y la convivencia a trav\u00e9s del lenguaje universal de la m\u00fasica.<\/li>\n<\/ul>\n\n\n\n<p><strong>Ideal para:<\/strong> Escuelas, centros culturales, fiestas mayores y eventos comunitarios que quieran celebrar la diversidad y el compromiso social de una forma alegre y profesional.<\/p>\n\n\n\n<div id='gallery-1' class='gallery galleryid-10453 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/32372652532_3a5753e39d_z.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/32372652532_3a5753e39d_z-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/32372653452_baa5462976_z.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/32372653452_baa5462976_z-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/32372656282_f467ea84fa_z.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/32372656282_f467ea84fa_z-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/49520528947_681fe0458e_b.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/49520528947_681fe0458e_b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2026\/03\/Karibu-Carles-Cuberes-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/karibu\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><li class=\"kb-query-item kb-query-block-post post-4085 artista type-artista status-publish has-post-thumbnail hentry espectaculos-cuentos\"><div class=\"kb-query-item-flip-back\"><\/div>\n<style>.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col,.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_62d054-cd4085{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_62d054-cd4085 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_62d054-cd4085 kb-section-has-link\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(25% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id4011_e355e2-b9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e355e2-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e355e2-b9 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col,.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_7b4cc4-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_7b4cc4-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_7b4cc4-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_adf94a-55:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image4011_adf94a-55 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_adf94a-55 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096206.jpg\" alt=\"\" width=\"537\" height=\"367\" class=\"kb-img wp-image-4086\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096206.jpg 537w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/teaserbox_2486096206-300x205.jpg 300w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_71740e-59 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col,.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_71740e-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_71740e-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_71740e-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_71740e-59{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_71740e-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_71740e-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:0px;text-align:left;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_9118ce-4f[data-kb-block=\"kb-adv-heading4011_9118ce-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4011_9118ce-4f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4011_9118ce-4f\">LA VERITAT HIST\u00d2RIA DEL REI QUE TENIA EL NAS VERMELL<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_35ec09-84[data-kb-block=\"kb-adv-heading4011_35ec09-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4011_35ec09-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_35ec09-84\"><p>+ 6 anys \u00b7 Catal\u00e0\/Castell\u00e0 \u00b7 45min (90min\/60min) \u00b7 4x3m \u00b7 2x240Watt (16A)<\/p>\n<\/div>\n\n\n<style>.wp-block-kadence-dynamichtml.kb-dynamic-html-id-4011_3f0f60-23.kb-dynamic-html:not(.added-for-specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}<\/style><div class=\"wp-block-kadence-dynamichtml kb-dynamic-html kb-dynamic-html-id-4011_3f0f60-23\">\n<p>Una divertida hist\u00f2ria que es desenvolupa al taulell d&#039;una antiga taverna un noi especial, on un simp\u00e0tic taverner ens explicar\u00e0 aquell conte medieval d&#039;un rei que tenia el nas vermell de tant de beure vi i que vol casar la seva filla; la princesa Roser, amb l&#039;home que a palau li porti el millor vi. La princesa ser\u00e0 obligada a casar-se sense amor per l&#039;egoisme del pare. A qui realment estima la princesa s&#039;a un pobre trobador\u2026<\/p>\n<\/div><\/div><\/div>\n\n<\/div><\/div><\/div><a href=\"https:\/\/lagreska.es\/ca\/artista\/la-veritable-historia-del-rei-que-tenia-el-nas-vermell\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/li><\/ul><\/div>\n<\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4011_e4f07c-9d > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id4011_e4f07c-9d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id4011_e4f07c-9d > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:100px;padding-bottom:100px;grid-template-columns:minmax(0, calc(60% - ((80px * 1 )\/2)))minmax(0, calc(40% - ((80px * 1 )\/2)));}.kb-row-layout-id4011_e4f07c-9d{background-color:rgba(216,124,145,0.82);}.kb-row-layout-id4011_e4f07c-9d > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id4011_e4f07c-9d .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id4011_e4f07c-9d .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id4011_e4f07c-9d .kt-row-layout-top-sep svg{fill:var(--global-palette8, #F7FAFC)!important;}@media all and (max-width: 1024px){.kb-row-layout-id4011_e4f07c-9d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4011_e4f07c-9d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id4011_e4f07c-9d .rounded-corners {  border-radius: 70px;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_e4f07c-9d alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-top-sep kt-row-sep-type-crvli\"><svg viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\"><path d=\"M1000,0c0,0 -420.987,98 -650,98c-229.013,0 -350,-98 -350,-98l0,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col,.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_9a0a41-a4{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_9a0a41-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_9a0a41-a4 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image4011_d205f2-ab:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:var(--global-kb-spacing-md, 2rem);}.kb-image4011_d205f2-ab .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image4011_d205f2-ab img.kb-img, .kb-image4011_d205f2-ab .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_d205f2-ab kb-image-is-ratio-size rounded-corners\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"495\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/8cdf5160-8040-4cfc-b193-519a25bacf6e_16-9-aspect-ratio_default_0.jpg\" alt=\"\" class=\"kb-img wp-image-5969\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/8cdf5160-8040-4cfc-b193-519a25bacf6e_16-9-aspect-ratio_default_0.jpg 880w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/8cdf5160-8040-4cfc-b193-519a25bacf6e_16-9-aspect-ratio_default_0-300x169.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/8cdf5160-8040-4cfc-b193-519a25bacf6e_16-9-aspect-ratio_default_0-768x432.jpg 768w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/div><\/figure>\n\n\n<style>.kb-row-layout-id4011_56425f-75 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4011_56425f-75 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4011_56425f-75 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:25px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4011_56425f-75 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4011_56425f-75 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4011_56425f-75 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4011_56425f-75 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column4011_0dc359-3b > .kt-inside-inner-col,.kadence-column4011_0dc359-3b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_0dc359-3b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_0dc359-3b > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_0dc359-3b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_0dc359-3b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_0dc359-3b{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_0dc359-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_0dc359-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_0dc359-3b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image4011_20fb08-9d .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image4011_20fb08-9d img.kb-img, .kb-image4011_20fb08-9d .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_20fb08-9d kb-image-is-ratio-size rounded-corners\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/14e8f099ae65c279abbbd36886500a14.jpg\" alt=\"\" class=\"kb-img wp-image-5968\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/14e8f099ae65c279abbbd36886500a14.jpg 1024w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/14e8f099ae65c279abbbd36886500a14-300x200.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/14e8f099ae65c279abbbd36886500a14-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4011_6325ab-31 > .kt-inside-inner-col,.kadence-column4011_6325ab-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_6325ab-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_6325ab-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_6325ab-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_6325ab-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_6325ab-31{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_6325ab-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_6325ab-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_6325ab-31 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image4011_98ef6f-1f .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image4011_98ef6f-1f img.kb-img, .kb-image4011_98ef6f-1f .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4011_98ef6f-1f size-full kb-image-is-ratio-size rounded-corners\"><div class=\"kb-is-ratio-image kb-image-ratio-land169\"><img loading=\"lazy\" decoding=\"async\" width=\"895\" height=\"619\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg\" alt=\"\" class=\"kb-img wp-image-4071\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg 895w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img-300x207.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img-768x531.jpg 768w\" sizes=\"auto, (max-width: 895px) 100vw, 895px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column4011_d2be66-99 > .kt-inside-inner-col,.kadence-column4011_d2be66-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4011_d2be66-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4011_d2be66-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4011_d2be66-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4011_d2be66-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4011_d2be66-99{position:relative;}@media all and (max-width: 1024px){.kadence-column4011_d2be66-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4011_d2be66-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4011_d2be66-99 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79, .wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79[data-kb-block=\"kb-adv-heading4011_c091d9-79\"]{margin-top:0px;text-align:left;font-weight:400;font-style:normal;font-family:'Lilita One';color:#202733;}.wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79[data-kb-block=\"kb-adv-heading4011_c091d9-79\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79[data-kb-block=\"kb-adv-heading4011_c091d9-79\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79, .wp-block-kadence-advancedheading.kt-adv-heading4011_c091d9-79[data-kb-block=\"kb-adv-heading4011_c091d9-79\"]{font-size:32px;}}<\/style>\n<h2 class=\"kt-adv-heading4011_c091d9-79 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_c091d9-79\">M\u00e0gia i fantasia pel teu esdeveniment!<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4011_e2924c-11, .wp-block-kadence-advancedheading.kt-adv-heading4011_e2924c-11[data-kb-block=\"kb-adv-heading4011_e2924c-11\"]{text-align:left;font-weight:300;font-style:normal;color:#1b2029;}.wp-block-kadence-advancedheading.kt-adv-heading4011_e2924c-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4011_e2924c-11[data-kb-block=\"kb-adv-heading4011_e2924c-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4011_e2924c-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4011_e2924c-11[data-kb-block=\"kb-adv-heading4011_e2924c-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading4011_e2924c-11 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4011_e2924c-11\">Submergeix-te en el meravell\u00f3s m\u00f3n dels contes amb La Greska Espectacles i viu una experi\u00e8ncia inoblidable plena de m\u00e0gia i diversi\u00f3 per a tota la fam\u00edlia! Contacta&#039;ns avui mateix per reservar el teu viatge a la fantasia.<\/p>\n\n\n<style>.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form textarea{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advanced-form3986-cpt-id{--kb-form-border-width:2px;--kb-form-border-color:var(--global-palette1, #3182CE);}@media all and (max-width: 1024px){.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form textarea{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form3986-cpt-id .kb-advanced-form textarea{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form3986-cpt-id kb-adv-form-label-style-normal kb-adv-form-input-size-small kb-form-basic-style wp-block-kadence-advanced-form\"><form id=\"kb-adv-form-3986-cpt-id\" class=\"kb-advanced-form\" method=\"post\" action=\"\">\n<style>.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-sm, 1rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3986_1bf7d7-03 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3986_1bf7d7-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3986_1bf7d7-03 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3986_b30672-90 > .kt-inside-inner-col,.kadence-column3986_b30672-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_b30672-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_b30672-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_b30672-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_b30672-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_b30672-90{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_b30672-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_b30672-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_b30672-90\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986f4fb11-e7 wp-block-kadence-advanced-form-text\"><input name=\"fieldf4fb11-e7\" id=\"field3986f4fb11-e7\" data-label=\"Nombre y Apellidos\" type=\"text\" placeholder=\"Nom i Cognoms\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Nom i Cognoms\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_d76a19-ed > .kt-inside-inner-col,.kadence-column3986_d76a19-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_d76a19-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_d76a19-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_d76a19-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_d76a19-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_d76a19-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_d76a19-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_d76a19-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_d76a19-ed\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986fcd365-83 wp-block-kadence-advanced-form-email\"><input name=\"fieldfcd365-83\" id=\"field3986fcd365-83\" data-label=\"Correo electr\u00f3nico\" type=\"email\" placeholder=\"Correu electr\u00f2nic\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Correu electr\u00f2nic\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col,.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_2d67dc-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_2d67dc-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_2d67dc-c0\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986c2f560-81 wp-block-kadence-advanced-form-telephone\"><input name=\"fieldc2f560-81\" id=\"field3986c2f560-81\" data-label=\"Tel\u00e9fono\" type=\"tel\" placeholder=\"Tel\u00e8fon\" value=\"\" data-type=\"tel\" class=\"kb-field kb-tel-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Tel\u00e8fon\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_c63fa2-08 > .kt-inside-inner-col,.kadence-column3986_c63fa2-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_c63fa2-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_c63fa2-08{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_c63fa2-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_c63fa2-08\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986138b5e-fd wp-block-kadence-advanced-form-text\"><input name=\"field138b5e-fd\" id=\"field3986138b5e-fd\" data-label=\"Prov\u00edncia\" type=\"text\" placeholder=\"Prov\u00edncia\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Prov\u00edncia\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col,.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_f7f44f-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_f7f44f-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_f7f44f-b5\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field39868762a4-7d wp-block-kadence-advanced-form-select\"><select  name=\"field8762a4-7d\" id=\"field39868762a4-7d\" required aria-required=\"true\" aria-label=\"Servei\"><option value=\"Espect\u00e1culo y animaci\u00f3n\">Espectacle i animaci\u00f3<\/option><option value=\"M\u00fasica para eventos\">M\u00fasica per a esdeveniments<\/option><option value=\"Parques y atracciones\">Parcs i atraccions<\/option><option value=\"Alquiler  de material\">Lloguer de material<\/option><option value=\"Organizaci\u00f3n de eventos\">Organitzaci\u00f3 d&#039;esdeveniments<\/option><\/select><\/div><\/div><\/div>\n\n\n<style>.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col,.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3986_c7c1a4-5e{position:relative;}@media all and (max-width: 1024px){.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3986_c7c1a4-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3986_c7c1a4-5e\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986aba617-98 wp-block-kadence-advanced-form-text\"><input name=\"fieldaba617-98\" id=\"field3986aba617-98\" data-label=\"Asunto\" type=\"text\" placeholder=\"Assumpte\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Assumpte\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field3986cc8e76-97 wp-block-kadence-advanced-form-textarea\"><textarea name=\"fieldcc8e76-97\" id=\"field3986cc8e76-97\" rows=\"3\"  data-label=\"Consulta\" placeholder=\"Consulta\" data-type=\"textarea\" class=\"kb-field kb-textarea-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Consulta\"><\/textarea><\/div>\n\n<div class=\"kb-adv-form-field kb-field39860ab9ec-bb wp-block-kadence-advanced-form-accept\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb39860ab9ec-bb\" data-type=\"accept\" data-required=\"yes\" ><legend class=\"screen-reader-text\">Privadesa<\/legend><div class=\"kb-radio-check-item\"><input name=\"field0ab9ec-bb\" id=\"field39860ab9ec-bb_0\" data-label=\"Privacidad\" type=\"checkbox\" value=\"accept\" data-type=\"accept\" class=\"kb-field kb-accept-field kb-checkbox-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Privadesa\"\/><label for=\"field39860ab9ec-bb_0\">He llegit i accepto les condicions contingudes a la <a href=\"https:\/\/lagreska.es\/ca\/politica-de-privacidad\/\" data-type=\"page\" data-id=\"10\">pol\u00edtica de privadesa<\/a> sobre el tractament de les meves dades per gestionar la meva consulta o petici\u00f3.<span class=\"kb-adv-form-required\">*<\/span><\/label><\/div><\/fieldset><\/div>\n\n<input type=\"hidden\" name=\"recaptcha_response\" class=\"kb_recaptcha_response kb_recaptcha_2d1c95-b1\" \/>\n\n<style>.kb-submit-field .kb-btn3087cc-e8.kb-button, ul.menu .kb-submit-field .kb-btn3087cc-e8.kb-button{width:200px;}.kb-submit-field .kb-btn3087cc-e8.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}.kb-submit-field .kb-btn3087cc-e8.kb-button:hover, .kb-submit-field .kb-btn3087cc-e8.kb-button:focus{color:var(--global-palette1, #3182CE);background:var(--global-palette9, #ffffff);}.kb-submit-field.kb-field3087cc-e8{justify-content:flex-start;}@media all and (max-width: 1024px){.kb-submit-field .kb-btn3087cc-e8.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.kb-submit-field .kb-btn3087cc-e8.kb-button{border-top:2px solid var(--global-palette1, #3182CE);border-right:2px solid var(--global-palette1, #3182CE);border-bottom:2px solid var(--global-palette1, #3182CE);border-left:2px solid var(--global-palette1, #3182CE);}}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-field3087cc-e8 wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btn3087cc-e8 kt-btn-size-standard kt-btn-width-type-fixed kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false\" type=\"submit\"><span class=\"kt-btn-inner-text\">Enviar<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"3986\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"3986-cpt-id\"><input type=\"hidden\" name=\"trp-form-language\" value=\"ca\"\/><\/form><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Viatja a un m\u00f3n de fantasia amb els nostres contes encantats! Deixa&#039;t embolicar per la m\u00e0gia dels contes amb La Greska Espectacles! Submergeix-te en un univers ple de rialles, emoci\u00f3 i aventures dissenyades especialment per als m\u00e9s petits i tota la fam\u00edlia. Des de divertides entremaliadures fins a impressionants il\u00b7lusions, cadascun dels nostres espectacles \u00e9s una\u2026<\/p>","protected":false},"author":1,"featured_media":4071,"parent":3682,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-4011","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuentos - La Greska Espectacles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/cuentos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuentos - La Greska Espectacles\" \/>\n<meta property=\"og:description\" content=\"\u00a1Viaja a un mundo de fantas\u00eda con nuestros cuentos encantados! \u00a1D\u00e9jate envolver por la magia de los cuentos con La Greska Espectacles! Sum\u00e9rgete en un universo lleno de risas, emoci\u00f3n y aventuras dise\u00f1adas especialmente para los m\u00e1s peque\u00f1os y toda la familia. Desde divertidas travesuras hasta impresionantes ilusiones, cada uno de nuestros espect\u00e1culos es una...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/cuentos\/\" \/>\n<meta property=\"og:site_name\" content=\"La Greska Espectacles\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T07:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"895\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/\",\"url\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/\",\"name\":\"Cuentos - La Greska Espectacles\",\"isPartOf\":{\"@id\":\"https:\/\/lagreska.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg\",\"datePublished\":\"2024-05-07T09:09:00+00:00\",\"dateModified\":\"2024-05-29T07:19:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#primaryimage\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg\",\"width\":895,\"height\":619},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lagreska.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espect\u00e1culos y Animaci\u00f3n\",\"item\":\"https:\/\/lagreska.es\/espectaculos-y-animacion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cuentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lagreska.es\/#website\",\"url\":\"https:\/\/lagreska.es\/\",\"name\":\"La Greska Espectacles\",\"description\":\"Agencia de animaci\u00f3n de fiestas y eventos en Sabadell\",\"publisher\":{\"@id\":\"https:\/\/lagreska.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lagreska.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lagreska.es\/#organization\",\"name\":\"La Greska Espectacles\",\"url\":\"https:\/\/lagreska.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":813,\"height\":307,\"caption\":\"La Greska Espectacles\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuentos - La Greska Espectacles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/cuentos\/","og_locale":"ca_ES","og_type":"article","og_title":"Cuentos - La Greska Espectacles","og_description":"\u00a1Viaja a un mundo de fantas\u00eda con nuestros cuentos encantados! \u00a1D\u00e9jate envolver por la magia de los cuentos con La Greska Espectacles! Sum\u00e9rgete en un universo lleno de risas, emoci\u00f3n y aventuras dise\u00f1adas especialmente para los m\u00e1s peque\u00f1os y toda la familia. Desde divertidas travesuras hasta impresionantes ilusiones, cada uno de nuestros espect\u00e1culos es una...","og_url":"https:\/\/lagreska.es\/ca\/espectaculos-y-animacion\/cuentos\/","og_site_name":"La Greska Espectacles","article_modified_time":"2024-05-29T07:19:55+00:00","og_image":[{"width":895,"height":619,"url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/","url":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/","name":"Cuentos - La Greska Espectacles","isPartOf":{"@id":"https:\/\/lagreska.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#primaryimage"},"image":{"@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#primaryimage"},"thumbnailUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg","datePublished":"2024-05-07T09:09:00+00:00","dateModified":"2024-05-29T07:19:55+00:00","breadcrumb":{"@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#primaryimage","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg","width":895,"height":619},{"@type":"BreadcrumbList","@id":"https:\/\/lagreska.es\/espectaculos-y-animacion\/cuentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagreska.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Espect\u00e1culos y Animaci\u00f3n","item":"https:\/\/lagreska.es\/espectaculos-y-animacion\/"},{"@type":"ListItem","position":3,"name":"Cuentos"}]},{"@type":"WebSite","@id":"https:\/\/lagreska.es\/#website","url":"https:\/\/lagreska.es\/","name":"La Greska Espectacles","description":"Ag\u00e8ncia d&#039;animaci\u00f3 de festes i esdeveniments a Sabadell","publisher":{"@id":"https:\/\/lagreska.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagreska.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagreska.es\/#organization","name":"La Greska Espectacles","url":"https:\/\/lagreska.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","width":813,"height":307,"caption":"La Greska Espectacles"},"image":{"@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/cuentos-img.jpg",895,619,false],"author_info":{"display_name":"eloi","author_link":"https:\/\/lagreska.es\/ca\/author\/eloi\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages\/4011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/comments?post=4011"}],"version-history":[{"count":0,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages\/4011\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/pages\/3682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media\/4071"}],"wp:attachment":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media?parent=4011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}