{"id":7716,"date":"2024-07-05T11:32:45","date_gmt":"2024-07-05T09:32:45","guid":{"rendered":"https:\/\/lagreska.es\/?post_type=atraccion&#038;p=7716"},"modified":"2024-07-05T11:32:46","modified_gmt":"2024-07-05T09:32:46","slug":"kubb","status":"publish","type":"atraccion","link":"https:\/\/lagreska.es\/ca\/atraccion\/kubb\/","title":{"rendered":"Kubb"},"content":{"rendered":"","protected":false},"featured_media":7717,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"parques-atracciones":[70,142],"class_list":["post-7716","atraccion","type-atraccion","status-publish","has-post-thumbnail","hentry","parques-atracciones-juegos","parques-atracciones-mundijuegos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kubb - La Greska Espectacles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagreska.es\/ca\/atraccion\/kubb\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kubb - La Greska Espectacles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagreska.es\/ca\/atraccion\/kubb\/\" \/>\n<meta property=\"og:site_name\" content=\"La Greska Espectacles\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T09:32:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"551\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lagreska.es\/atraccion\/kubb\/\",\"url\":\"https:\/\/lagreska.es\/atraccion\/kubb\/\",\"name\":\"Kubb - La Greska Espectacles\",\"isPartOf\":{\"@id\":\"https:\/\/lagreska.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lagreska.es\/atraccion\/kubb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/atraccion\/kubb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png\",\"datePublished\":\"2024-07-05T09:32:45+00:00\",\"dateModified\":\"2024-07-05T09:32:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lagreska.es\/atraccion\/kubb\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lagreska.es\/atraccion\/kubb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/atraccion\/kubb\/#primaryimage\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png\",\"width\":800,\"height\":551},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lagreska.es\/atraccion\/kubb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lagreska.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kubb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lagreska.es\/#website\",\"url\":\"https:\/\/lagreska.es\/\",\"name\":\"La Greska Espectacles\",\"description\":\"Agencia de animaci\u00f3n de fiestas y eventos en Sabadell\",\"publisher\":{\"@id\":\"https:\/\/lagreska.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lagreska.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lagreska.es\/#organization\",\"name\":\"La Greska Espectacles\",\"url\":\"https:\/\/lagreska.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":813,\"height\":307,\"caption\":\"La Greska Espectacles\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kubb - La Greska Espectacles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagreska.es\/ca\/atraccion\/kubb\/","og_locale":"ca_ES","og_type":"article","og_title":"Kubb - La Greska Espectacles","og_url":"https:\/\/lagreska.es\/ca\/atraccion\/kubb\/","og_site_name":"La Greska Espectacles","article_modified_time":"2024-07-05T09:32:46+00:00","og_image":[{"width":800,"height":551,"url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagreska.es\/atraccion\/kubb\/","url":"https:\/\/lagreska.es\/atraccion\/kubb\/","name":"Kubb - La Greska Espectacles","isPartOf":{"@id":"https:\/\/lagreska.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagreska.es\/atraccion\/kubb\/#primaryimage"},"image":{"@id":"https:\/\/lagreska.es\/atraccion\/kubb\/#primaryimage"},"thumbnailUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png","datePublished":"2024-07-05T09:32:45+00:00","dateModified":"2024-07-05T09:32:46+00:00","breadcrumb":{"@id":"https:\/\/lagreska.es\/atraccion\/kubb\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagreska.es\/atraccion\/kubb\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/atraccion\/kubb\/#primaryimage","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png","width":800,"height":551},{"@type":"BreadcrumbList","@id":"https:\/\/lagreska.es\/atraccion\/kubb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagreska.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Kubb"}]},{"@type":"WebSite","@id":"https:\/\/lagreska.es\/#website","url":"https:\/\/lagreska.es\/","name":"La Greska Espectacles","description":"Ag\u00e8ncia d&#039;animaci\u00f3 de festes i esdeveniments a Sabadell","publisher":{"@id":"https:\/\/lagreska.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagreska.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagreska.es\/#organization","name":"La Greska Espectacles","url":"https:\/\/lagreska.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","width":813,"height":307,"caption":"La Greska Espectacles"},"image":{"@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"parques-atracciones":[{"value":70,"label":"Juegos"},{"value":142,"label":"MundiJuegos"}]},"featured_image_src_large":["https:\/\/lagreska.es\/wp-content\/uploads\/2024\/07\/imagen_2024-07-05_113232280.png",800,551,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion\/7716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion"}],"about":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/types\/atraccion"}],"version-history":[{"count":0,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion\/7716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media\/7717"}],"wp:attachment":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media?parent=7716"}],"wp:term":[{"taxonomy":"parques-atracciones","embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/parques-atracciones?post=7716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}