{"id":6083,"date":"2024-06-11T08:18:41","date_gmt":"2024-06-11T06:18:41","guid":{"rendered":"https:\/\/lagreska.es\/?post_type=atraccion&#038;p=6083"},"modified":"2025-07-28T21:51:06","modified_gmt":"2025-07-28T19:51:06","slug":"palmeras","status":"publish","type":"atraccion","link":"https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/","title":{"rendered":"Palmeres"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Doble Diversi\u00f3 Aqu\u00e0tica amb El nostre Inflable de Pistes Tropicals!<\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6083_846263-00, .wp-block-kadence-advancedheading.kt-adv-heading6083_846263-00[data-kb-block=\"kb-adv-heading6083_846263-00\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6083_846263-00 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6083_846263-00[data-kb-block=\"kb-adv-heading6083_846263-00\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6083_846263-00 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6083_846263-00[data-kb-block=\"kb-adv-heading6083_846263-00\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6083_846263-00 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6083_846263-00\">Transforma el teu esdeveniment en un oasi amb el nostre inflable de doble pista, decorat amb palmeres i arcs iris. Perfecte per a refrescants carreres i capbussades!<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6083_ce8f6c-0e, .wp-block-kadence-advancedheading.kt-adv-heading6083_ce8f6c-0e[data-kb-block=\"kb-adv-heading6083_ce8f6c-0e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6083_ce8f6c-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6083_ce8f6c-0e[data-kb-block=\"kb-adv-heading6083_ce8f6c-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6083_ce8f6c-0e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6083_ce8f6c-0e[data-kb-block=\"kb-adv-heading6083_ce8f6c-0e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6083_ce8f6c-0e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6083_ce8f6c-0e\">Amb dos carrils de lliscament i una zona d\u00b4aterratge aqu\u00e0tica, \u00e9s ideal per a totes les edats. Fabricat per a la m\u00e0xima diversi\u00f3 i seguretat.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6083_e13f3a-cc, .wp-block-kadence-advancedheading.kt-adv-heading6083_e13f3a-cc[data-kb-block=\"kb-adv-heading6083_e13f3a-cc\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6083_e13f3a-cc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6083_e13f3a-cc[data-kb-block=\"kb-adv-heading6083_e13f3a-cc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6083_e13f3a-cc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6083_e13f3a-cc[data-kb-block=\"kb-adv-heading6083_e13f3a-cc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6083_e13f3a-cc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6083_e13f3a-cc\">Reserva-ho ja i garanteix l&#039;\u00e8xit de la teva celebraci\u00f3!<\/p>\n\n\n\n<div id='gallery-1' class='gallery galleryid-6083 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/fb_img_1593958577749\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/FB_IMG_1593958577749-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/FB_IMG_1593958577749-150x150.jpg 150w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/FB_IMG_1593958577749-300x300.jpg 300w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/FB_IMG_1593958577749-768x768.jpg 768w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/FB_IMG_1593958577749-12x12.jpg 12w, https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/FB_IMG_1593958577749.jpg 830w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/img_20200702_083550\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/IMG_20200702_083550-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/img_20200702_083743\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/IMG_20200702_083743-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/img-20200723-wa0016\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/IMG-20200723-WA0016-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n\n\n\n<p><\/p>","protected":false},"featured_media":6086,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"parques-atracciones":[112,66],"class_list":["post-6083","atraccion","type-atraccion","status-publish","has-post-thumbnail","hentry","parques-atracciones-deslizador-hinchables-acuaticos","parques-atracciones-hinchables-acuaticos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palmeras - La Greska Espectacles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palmeras - La Greska Espectacles\" \/>\n<meta property=\"og:description\" content=\"\u00a1Doble Diversi\u00f3n Acu\u00e1tica con Nuestro Hinchable de Pistas Tropicales! Transforma tu evento en un oasis con nuestro hinchable de doble pista, decorado con palmeras y arco\u00edris. \u00a1Perfecto para refrescantes carreras y chapuzones! Con dos carriles de deslizamiento y una zona de aterrizaje acu\u00e1tica, es ideal para todas las edades. Fabricado para la m\u00e1xima diversi\u00f3n y...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/\" \/>\n<meta property=\"og:site_name\" content=\"La Greska Espectacles\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T19:51:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"551\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/\",\"url\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/\",\"name\":\"Palmeras - La Greska Espectacles\",\"isPartOf\":{\"@id\":\"https:\/\/lagreska.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png\",\"datePublished\":\"2024-06-11T06:18:41+00:00\",\"dateModified\":\"2025-07-28T19:51:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lagreska.es\/atraccion\/palmeras\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/#primaryimage\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png\",\"width\":800,\"height\":551},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lagreska.es\/atraccion\/palmeras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lagreska.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palmeras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lagreska.es\/#website\",\"url\":\"https:\/\/lagreska.es\/\",\"name\":\"La Greska Espectacles\",\"description\":\"Agencia de animaci\u00f3n de fiestas y eventos en Sabadell\",\"publisher\":{\"@id\":\"https:\/\/lagreska.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lagreska.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lagreska.es\/#organization\",\"name\":\"La Greska Espectacles\",\"url\":\"https:\/\/lagreska.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":813,\"height\":307,\"caption\":\"La Greska Espectacles\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palmeras - La Greska Espectacles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/","og_locale":"ca_ES","og_type":"article","og_title":"Palmeras - La Greska Espectacles","og_description":"\u00a1Doble Diversi\u00f3n Acu\u00e1tica con Nuestro Hinchable de Pistas Tropicales! Transforma tu evento en un oasis con nuestro hinchable de doble pista, decorado con palmeras y arco\u00edris. \u00a1Perfecto para refrescantes carreras y chapuzones! Con dos carriles de deslizamiento y una zona de aterrizaje acu\u00e1tica, es ideal para todas las edades. Fabricado para la m\u00e1xima diversi\u00f3n y...","og_url":"https:\/\/lagreska.es\/ca\/atraccion\/palmeras\/","og_site_name":"La Greska Espectacles","article_modified_time":"2025-07-28T19:51:06+00:00","og_image":[{"width":800,"height":551,"url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagreska.es\/atraccion\/palmeras\/","url":"https:\/\/lagreska.es\/atraccion\/palmeras\/","name":"Palmeras - La Greska Espectacles","isPartOf":{"@id":"https:\/\/lagreska.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagreska.es\/atraccion\/palmeras\/#primaryimage"},"image":{"@id":"https:\/\/lagreska.es\/atraccion\/palmeras\/#primaryimage"},"thumbnailUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png","datePublished":"2024-06-11T06:18:41+00:00","dateModified":"2025-07-28T19:51:06+00:00","breadcrumb":{"@id":"https:\/\/lagreska.es\/atraccion\/palmeras\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagreska.es\/atraccion\/palmeras\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/atraccion\/palmeras\/#primaryimage","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png","width":800,"height":551},{"@type":"BreadcrumbList","@id":"https:\/\/lagreska.es\/atraccion\/palmeras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagreska.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Palmeras"}]},{"@type":"WebSite","@id":"https:\/\/lagreska.es\/#website","url":"https:\/\/lagreska.es\/","name":"La Greska Espectacles","description":"Ag\u00e8ncia d&#039;animaci\u00f3 de festes i esdeveniments a Sabadell","publisher":{"@id":"https:\/\/lagreska.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagreska.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagreska.es\/#organization","name":"La Greska Espectacles","url":"https:\/\/lagreska.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","width":813,"height":307,"caption":"La Greska Espectacles"},"image":{"@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"parques-atracciones":[{"value":112,"label":"Deslizador"},{"value":66,"label":"Hinchables acu\u00e1ticos"}]},"featured_image_src_large":["https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/Palmeras.png",800,551,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion\/6083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion"}],"about":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/types\/atraccion"}],"version-history":[{"count":4,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion\/6083\/revisions"}],"predecessor-version":[{"id":9868,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/atraccion\/6083\/revisions\/9868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media\/6086"}],"wp:attachment":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media?parent=6083"}],"wp:term":[{"taxonomy":"parques-atracciones","embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/parques-atracciones?post=6083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}