{"id":7141,"date":"2024-06-11T14:28:55","date_gmt":"2024-06-11T12:28:55","guid":{"rendered":"https:\/\/lagreska.es\/?post_type=alquiler-material&#038;p=7141"},"modified":"2024-12-08T23:14:40","modified_gmt":"2024-12-08T22:14:40","slug":"cuadro-electrico-220v","status":"publish","type":"alquiler-material","link":"https:\/\/lagreska.es\/ca\/alquiler-material\/cuadro-electrico-220v\/","title":{"rendered":"Quadre Electrico 220V"},"content":{"rendered":"<p>Els nostres Quadres Electrics 220V s\u00f3n Caixes provisionals Homologades amb per al seu \u00fas com a distribu\u00efdor de corrent en esdeveniments, fires i instal\u00b7lacions ef\u00edmeres. Amb Entrada Monof\u00e0sica o Trif\u00e0sica amb Presa CETAC, i sortides Monof\u00e0siques a schuko.<\/p>\n\n\n\n<p><\/p>","protected":false},"featured_media":7146,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"material":[135],"class_list":["post-7141","alquiler-material","type-alquiler-material","status-publish","has-post-thumbnail","hentry","material-electricidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuadro Electrico 220V - La Greska Espectacles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagreska.es\/ca\/alquiler-material\/cuadro-electrico-220v\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuadro Electrico 220V - La Greska Espectacles\" \/>\n<meta property=\"og:description\" content=\"Nuestros Cuadros Electricos 220V son Cajas provisionales Homologadas con para su uso como distribuidor de corriente en eventos, ferias e instalaciones ef\u00edmeras. Con Entrada Monof\u00e1sica o Trif\u00e1sica con Toma CETAC, i salidas Monofasicas en schuko.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagreska.es\/ca\/alquiler-material\/cuadro-electrico-220v\/\" \/>\n<meta property=\"og:site_name\" content=\"La Greska Espectacles\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-08T22:14:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"551\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/\",\"url\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/\",\"name\":\"Cuadro Electrico 220V - La Greska Espectacles\",\"isPartOf\":{\"@id\":\"https:\/\/lagreska.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg\",\"datePublished\":\"2024-06-11T12:28:55+00:00\",\"dateModified\":\"2024-12-08T22:14:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#primaryimage\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg\",\"width\":800,\"height\":551},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lagreska.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuadro Electrico 220V\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lagreska.es\/#website\",\"url\":\"https:\/\/lagreska.es\/\",\"name\":\"La Greska Espectacles\",\"description\":\"Agencia de animaci\u00f3n de fiestas y eventos en Sabadell\",\"publisher\":{\"@id\":\"https:\/\/lagreska.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lagreska.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lagreska.es\/#organization\",\"name\":\"La Greska Espectacles\",\"url\":\"https:\/\/lagreska.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":813,\"height\":307,\"caption\":\"La Greska Espectacles\"},\"image\":{\"@id\":\"https:\/\/lagreska.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuadro Electrico 220V - La Greska Espectacles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagreska.es\/ca\/alquiler-material\/cuadro-electrico-220v\/","og_locale":"ca_ES","og_type":"article","og_title":"Cuadro Electrico 220V - La Greska Espectacles","og_description":"Nuestros Cuadros Electricos 220V son Cajas provisionales Homologadas con para su uso como distribuidor de corriente en eventos, ferias e instalaciones ef\u00edmeras. Con Entrada Monof\u00e1sica o Trif\u00e1sica con Toma CETAC, i salidas Monofasicas en schuko.","og_url":"https:\/\/lagreska.es\/ca\/alquiler-material\/cuadro-electrico-220v\/","og_site_name":"La Greska Espectacles","article_modified_time":"2024-12-08T22:14:40+00:00","og_image":[{"width":800,"height":551,"url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/","url":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/","name":"Cuadro Electrico 220V - La Greska Espectacles","isPartOf":{"@id":"https:\/\/lagreska.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#primaryimage"},"image":{"@id":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#primaryimage"},"thumbnailUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg","datePublished":"2024-06-11T12:28:55+00:00","dateModified":"2024-12-08T22:14:40+00:00","breadcrumb":{"@id":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#primaryimage","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg","width":800,"height":551},{"@type":"BreadcrumbList","@id":"https:\/\/lagreska.es\/alquiler-material\/cuadro-electrico-220v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lagreska.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cuadro Electrico 220V"}]},{"@type":"WebSite","@id":"https:\/\/lagreska.es\/#website","url":"https:\/\/lagreska.es\/","name":"La Greska Espectacles","description":"Ag\u00e8ncia d&#039;animaci\u00f3 de festes i esdeveniments a Sabadell","publisher":{"@id":"https:\/\/lagreska.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagreska.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lagreska.es\/#organization","name":"La Greska Espectacles","url":"https:\/\/lagreska.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/","url":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/lagreska.es\/wp-content\/uploads\/2024\/05\/logo.png","width":813,"height":307,"caption":"La Greska Espectacles"},"image":{"@id":"https:\/\/lagreska.es\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"material":[{"value":135,"label":"Electricidad"}]},"featured_image_src_large":["https:\/\/lagreska.es\/wp-content\/uploads\/2024\/06\/cache_2492562859.jpg",800,551,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/alquiler-material\/7141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/alquiler-material"}],"about":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/types\/alquiler-material"}],"version-history":[{"count":1,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/alquiler-material\/7141\/revisions"}],"predecessor-version":[{"id":9466,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/alquiler-material\/7141\/revisions\/9466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media\/7146"}],"wp:attachment":[{"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/media?parent=7141"}],"wp:term":[{"taxonomy":"material","embeddable":true,"href":"https:\/\/lagreska.es\/ca\/wp-json\/wp\/v2\/material?post=7141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}